{"id":106833,"date":"2020-08-10T11:15:25","date_gmt":"2020-08-10T09:15:25","guid":{"rendered":"https:\/\/www.desmomarket.com\/?post_type=product&#038;p=106833"},"modified":"2020-08-10T11:15:26","modified_gmt":"2020-08-10T09:15:26","slug":"right-side-coil-cover-ducati-scrambler-2","status":"publish","type":"product","link":"https:\/\/www.desmomarket.com\/en\/product\/right-side-coil-cover-ducati-scrambler-2\/","title":{"rendered":"Right side coil cover ducati scrambler"},"content":{"rendered":"<p>very good conditions<\/p>\n","protected":false},"excerpt":{"rendered":"<p>very good conditions<\/p>\n","protected":false},"featured_media":111930,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"_joinchat":[]},"product_brand":[],"product_cat":[274],"product_tag":[135],"class_list":{"0":"post-106833","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-ducati-scrambler-800-en","7":"product_tag-secondhand","9":"first","10":"instock","11":"taxable","12":"shipping-taxable","13":"purchasable","14":"product-type-simple"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Right side coil cover ducati scrambler - Desmo Market<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.desmomarket.com\/en\/product\/right-side-coil-cover-ducati-scrambler-2\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Right side coil cover ducati scrambler - Desmo Market\" \/>\n<meta property=\"og:description\" content=\"very good conditions\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.desmomarket.com\/en\/product\/right-side-coil-cover-ducati-scrambler-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Desmo Market\" \/>\n<meta property=\"article:modified_time\" content=\"2020-08-10T09:15:26+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.desmomarket.com\/wp-content\/uploads\/2020\/08\/cover-coperchio-bobina-destro-ducati-scrambler_1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1280\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.desmomarket.com\\\/en\\\/product\\\/right-side-coil-cover-ducati-scrambler-2\\\/\",\"url\":\"https:\\\/\\\/www.desmomarket.com\\\/en\\\/product\\\/right-side-coil-cover-ducati-scrambler-2\\\/\",\"name\":\"Right side coil cover ducati scrambler - Desmo Market\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.desmomarket.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.desmomarket.com\\\/en\\\/product\\\/right-side-coil-cover-ducati-scrambler-2\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.desmomarket.com\\\/en\\\/product\\\/right-side-coil-cover-ducati-scrambler-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.desmomarket.com\\\/wp-content\\\/uploads\\\/2020\\\/08\\\/cover-coperchio-bobina-destro-ducati-scrambler_1.jpg\",\"datePublished\":\"2020-08-10T09:15:25+00:00\",\"dateModified\":\"2020-08-10T09:15:26+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.desmomarket.com\\\/en\\\/product\\\/right-side-coil-cover-ducati-scrambler-2\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.desmomarket.com\\\/en\\\/product\\\/right-side-coil-cover-ducati-scrambler-2\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.desmomarket.com\\\/en\\\/product\\\/right-side-coil-cover-ducati-scrambler-2\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.desmomarket.com\\\/wp-content\\\/uploads\\\/2020\\\/08\\\/cover-coperchio-bobina-destro-ducati-scrambler_1.jpg\",\"contentUrl\":\"https:\\\/\\\/www.desmomarket.com\\\/wp-content\\\/uploads\\\/2020\\\/08\\\/cover-coperchio-bobina-destro-ducati-scrambler_1.jpg\",\"width\":1920,\"height\":1280},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.desmomarket.com\\\/en\\\/product\\\/right-side-coil-cover-ducati-scrambler-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.desmomarket.com\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/www.desmomarket.com\\\/en\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Right side coil cover ducati scrambler\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.desmomarket.com\\\/#website\",\"url\":\"https:\\\/\\\/www.desmomarket.com\\\/\",\"name\":\"Desmo Market\",\"description\":\"Spare parts\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.desmomarket.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.desmomarket.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.desmomarket.com\\\/#organization\",\"name\":\"Desmo Market s.a.s.\",\"url\":\"https:\\\/\\\/www.desmomarket.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.desmomarket.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.desmomarket.com\\\/wp-content\\\/uploads\\\/2017\\\/12\\\/60-x-60-Desmo-Market.png\",\"contentUrl\":\"https:\\\/\\\/www.desmomarket.com\\\/wp-content\\\/uploads\\\/2017\\\/12\\\/60-x-60-Desmo-Market.png\",\"width\":710,\"height\":710,\"caption\":\"Desmo Market s.a.s.\"},\"image\":{\"@id\":\"https:\\\/\\\/www.desmomarket.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Right side coil cover ducati scrambler - Desmo Market","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.desmomarket.com\/en\/product\/right-side-coil-cover-ducati-scrambler-2\/","og_locale":"en_US","og_type":"article","og_title":"Right side coil cover ducati scrambler - Desmo Market","og_description":"very good conditions","og_url":"https:\/\/www.desmomarket.com\/en\/product\/right-side-coil-cover-ducati-scrambler-2\/","og_site_name":"Desmo Market","article_modified_time":"2020-08-10T09:15:26+00:00","og_image":[{"width":1920,"height":1280,"url":"https:\/\/www.desmomarket.com\/wp-content\/uploads\/2020\/08\/cover-coperchio-bobina-destro-ducati-scrambler_1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.desmomarket.com\/en\/product\/right-side-coil-cover-ducati-scrambler-2\/","url":"https:\/\/www.desmomarket.com\/en\/product\/right-side-coil-cover-ducati-scrambler-2\/","name":"Right side coil cover ducati scrambler - Desmo Market","isPartOf":{"@id":"https:\/\/www.desmomarket.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.desmomarket.com\/en\/product\/right-side-coil-cover-ducati-scrambler-2\/#primaryimage"},"image":{"@id":"https:\/\/www.desmomarket.com\/en\/product\/right-side-coil-cover-ducati-scrambler-2\/#primaryimage"},"thumbnailUrl":"https:\/\/www.desmomarket.com\/wp-content\/uploads\/2020\/08\/cover-coperchio-bobina-destro-ducati-scrambler_1.jpg","datePublished":"2020-08-10T09:15:25+00:00","dateModified":"2020-08-10T09:15:26+00:00","breadcrumb":{"@id":"https:\/\/www.desmomarket.com\/en\/product\/right-side-coil-cover-ducati-scrambler-2\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.desmomarket.com\/en\/product\/right-side-coil-cover-ducati-scrambler-2\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.desmomarket.com\/en\/product\/right-side-coil-cover-ducati-scrambler-2\/#primaryimage","url":"https:\/\/www.desmomarket.com\/wp-content\/uploads\/2020\/08\/cover-coperchio-bobina-destro-ducati-scrambler_1.jpg","contentUrl":"https:\/\/www.desmomarket.com\/wp-content\/uploads\/2020\/08\/cover-coperchio-bobina-destro-ducati-scrambler_1.jpg","width":1920,"height":1280},{"@type":"BreadcrumbList","@id":"https:\/\/www.desmomarket.com\/en\/product\/right-side-coil-cover-ducati-scrambler-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.desmomarket.com\/en\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/www.desmomarket.com\/en\/shop\/"},{"@type":"ListItem","position":3,"name":"Right side coil cover ducati scrambler"}]},{"@type":"WebSite","@id":"https:\/\/www.desmomarket.com\/#website","url":"https:\/\/www.desmomarket.com\/","name":"Desmo Market","description":"Spare parts","publisher":{"@id":"https:\/\/www.desmomarket.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.desmomarket.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.desmomarket.com\/#organization","name":"Desmo Market s.a.s.","url":"https:\/\/www.desmomarket.com\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.desmomarket.com\/#\/schema\/logo\/image\/","url":"https:\/\/www.desmomarket.com\/wp-content\/uploads\/2017\/12\/60-x-60-Desmo-Market.png","contentUrl":"https:\/\/www.desmomarket.com\/wp-content\/uploads\/2017\/12\/60-x-60-Desmo-Market.png","width":710,"height":710,"caption":"Desmo Market s.a.s."},"image":{"@id":"https:\/\/www.desmomarket.com\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.desmomarket.com\/en\/wp-json\/wp\/v2\/product\/106833","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.desmomarket.com\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.desmomarket.com\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/www.desmomarket.com\/en\/wp-json\/wp\/v2\/comments?post=106833"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.desmomarket.com\/en\/wp-json\/wp\/v2\/media\/111930"}],"wp:attachment":[{"href":"https:\/\/www.desmomarket.com\/en\/wp-json\/wp\/v2\/media?parent=106833"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.desmomarket.com\/en\/wp-json\/wp\/v2\/product_brand?post=106833"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.desmomarket.com\/en\/wp-json\/wp\/v2\/product_cat?post=106833"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.desmomarket.com\/en\/wp-json\/wp\/v2\/product_tag?post=106833"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}