{"id":606550,"date":"2026-07-16T09:22:50","date_gmt":"2026-07-16T07:22:50","guid":{"rendered":"https:\/\/www.desmomarket.com\/prodotto\/passenger-handle-ducati-supersport-750-800-900-1000\/"},"modified":"2026-07-16T09:23:17","modified_gmt":"2026-07-16T07:23:17","slug":"passenger-handle-ducati-supersport-750-800-900-1000-4","status":"publish","type":"product","link":"https:\/\/www.desmomarket.com\/en\/product\/passenger-handle-ducati-supersport-750-800-900-1000-4\/","title":{"rendered":"Passenger handle Ducati Supersport 750 800 900 1000"},"content":{"rendered":"<p>Used in good condition<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Used in good condition<\/p>\n","protected":false},"featured_media":606537,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"_glsr_average":0,"_glsr_ranking":0,"_glsr_reviews":0,"_joinchat":[]},"product_brand":[],"product_cat":[325],"product_tag":[135],"class_list":{"0":"post-606550","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-ducati-super-sport-ss-620-750-800-900-1000-en","7":"product_tag-secondhand","9":"first","10":"instock","11":"taxable","12":"shipping-taxable","13":"purchasable","14":"product-type-simple"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Passenger handle Ducati Supersport 750 800 900 1000 - Desmo Market<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.desmomarket.com\/en\/product\/passenger-handle-ducati-supersport-750-800-900-1000-4\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Passenger handle Ducati Supersport 750 800 900 1000 - Desmo Market\" \/>\n<meta property=\"og:description\" content=\"Used in good condition\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.desmomarket.com\/en\/product\/passenger-handle-ducati-supersport-750-800-900-1000-4\/\" \/>\n<meta property=\"og:site_name\" content=\"Desmo Market\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-16T07:23:17+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.desmomarket.com\/wp-content\/uploads\/2026\/07\/IMG_9511-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1706\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.desmomarket.com\\\/en\\\/product\\\/passenger-handle-ducati-supersport-750-800-900-1000-4\\\/\",\"url\":\"https:\\\/\\\/www.desmomarket.com\\\/en\\\/product\\\/passenger-handle-ducati-supersport-750-800-900-1000-4\\\/\",\"name\":\"Passenger handle Ducati Supersport 750 800 900 1000 - Desmo Market\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.desmomarket.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.desmomarket.com\\\/en\\\/product\\\/passenger-handle-ducati-supersport-750-800-900-1000-4\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.desmomarket.com\\\/en\\\/product\\\/passenger-handle-ducati-supersport-750-800-900-1000-4\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.desmomarket.com\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/IMG_9511-scaled.jpg\",\"datePublished\":\"2026-07-16T07:22:50+00:00\",\"dateModified\":\"2026-07-16T07:23:17+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.desmomarket.com\\\/en\\\/product\\\/passenger-handle-ducati-supersport-750-800-900-1000-4\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.desmomarket.com\\\/en\\\/product\\\/passenger-handle-ducati-supersport-750-800-900-1000-4\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.desmomarket.com\\\/en\\\/product\\\/passenger-handle-ducati-supersport-750-800-900-1000-4\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.desmomarket.com\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/IMG_9511-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/www.desmomarket.com\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/IMG_9511-scaled.jpg\",\"width\":2560,\"height\":1706},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.desmomarket.com\\\/en\\\/product\\\/passenger-handle-ducati-supersport-750-800-900-1000-4\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.desmomarket.com\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/www.desmomarket.com\\\/en\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Passenger handle Ducati Supersport 750 800 900 1000\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.desmomarket.com\\\/#website\",\"url\":\"https:\\\/\\\/www.desmomarket.com\\\/\",\"name\":\"Desmo Market\",\"description\":\"Spare parts\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.desmomarket.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.desmomarket.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.desmomarket.com\\\/#organization\",\"name\":\"Desmo Market s.a.s.\",\"url\":\"https:\\\/\\\/www.desmomarket.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.desmomarket.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.desmomarket.com\\\/wp-content\\\/uploads\\\/2017\\\/12\\\/60-x-60-Desmo-Market.png\",\"contentUrl\":\"https:\\\/\\\/www.desmomarket.com\\\/wp-content\\\/uploads\\\/2017\\\/12\\\/60-x-60-Desmo-Market.png\",\"width\":710,\"height\":710,\"caption\":\"Desmo Market s.a.s.\"},\"image\":{\"@id\":\"https:\\\/\\\/www.desmomarket.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Passenger handle Ducati Supersport 750 800 900 1000 - Desmo Market","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.desmomarket.com\/en\/product\/passenger-handle-ducati-supersport-750-800-900-1000-4\/","og_locale":"en_US","og_type":"article","og_title":"Passenger handle Ducati Supersport 750 800 900 1000 - Desmo Market","og_description":"Used in good condition","og_url":"https:\/\/www.desmomarket.com\/en\/product\/passenger-handle-ducati-supersport-750-800-900-1000-4\/","og_site_name":"Desmo Market","article_modified_time":"2026-07-16T07:23:17+00:00","og_image":[{"width":2560,"height":1706,"url":"https:\/\/www.desmomarket.com\/wp-content\/uploads\/2026\/07\/IMG_9511-scaled.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.desmomarket.com\/en\/product\/passenger-handle-ducati-supersport-750-800-900-1000-4\/","url":"https:\/\/www.desmomarket.com\/en\/product\/passenger-handle-ducati-supersport-750-800-900-1000-4\/","name":"Passenger handle Ducati Supersport 750 800 900 1000 - Desmo Market","isPartOf":{"@id":"https:\/\/www.desmomarket.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.desmomarket.com\/en\/product\/passenger-handle-ducati-supersport-750-800-900-1000-4\/#primaryimage"},"image":{"@id":"https:\/\/www.desmomarket.com\/en\/product\/passenger-handle-ducati-supersport-750-800-900-1000-4\/#primaryimage"},"thumbnailUrl":"https:\/\/www.desmomarket.com\/wp-content\/uploads\/2026\/07\/IMG_9511-scaled.jpg","datePublished":"2026-07-16T07:22:50+00:00","dateModified":"2026-07-16T07:23:17+00:00","breadcrumb":{"@id":"https:\/\/www.desmomarket.com\/en\/product\/passenger-handle-ducati-supersport-750-800-900-1000-4\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.desmomarket.com\/en\/product\/passenger-handle-ducati-supersport-750-800-900-1000-4\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.desmomarket.com\/en\/product\/passenger-handle-ducati-supersport-750-800-900-1000-4\/#primaryimage","url":"https:\/\/www.desmomarket.com\/wp-content\/uploads\/2026\/07\/IMG_9511-scaled.jpg","contentUrl":"https:\/\/www.desmomarket.com\/wp-content\/uploads\/2026\/07\/IMG_9511-scaled.jpg","width":2560,"height":1706},{"@type":"BreadcrumbList","@id":"https:\/\/www.desmomarket.com\/en\/product\/passenger-handle-ducati-supersport-750-800-900-1000-4\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.desmomarket.com\/en\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/www.desmomarket.com\/en\/shop\/"},{"@type":"ListItem","position":3,"name":"Passenger handle Ducati Supersport 750 800 900 1000"}]},{"@type":"WebSite","@id":"https:\/\/www.desmomarket.com\/#website","url":"https:\/\/www.desmomarket.com\/","name":"Desmo Market","description":"Spare parts","publisher":{"@id":"https:\/\/www.desmomarket.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.desmomarket.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.desmomarket.com\/#organization","name":"Desmo Market s.a.s.","url":"https:\/\/www.desmomarket.com\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.desmomarket.com\/#\/schema\/logo\/image\/","url":"https:\/\/www.desmomarket.com\/wp-content\/uploads\/2017\/12\/60-x-60-Desmo-Market.png","contentUrl":"https:\/\/www.desmomarket.com\/wp-content\/uploads\/2017\/12\/60-x-60-Desmo-Market.png","width":710,"height":710,"caption":"Desmo Market s.a.s."},"image":{"@id":"https:\/\/www.desmomarket.com\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.desmomarket.com\/en\/wp-json\/wp\/v2\/product\/606550","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.desmomarket.com\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.desmomarket.com\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/www.desmomarket.com\/en\/wp-json\/wp\/v2\/comments?post=606550"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.desmomarket.com\/en\/wp-json\/wp\/v2\/media\/606537"}],"wp:attachment":[{"href":"https:\/\/www.desmomarket.com\/en\/wp-json\/wp\/v2\/media?parent=606550"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.desmomarket.com\/en\/wp-json\/wp\/v2\/product_brand?post=606550"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.desmomarket.com\/en\/wp-json\/wp\/v2\/product_cat?post=606550"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.desmomarket.com\/en\/wp-json\/wp\/v2\/product_tag?post=606550"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}